{"id":6170,"date":"2025-02-20T15:11:36","date_gmt":"2025-02-20T15:11:36","guid":{"rendered":"https:\/\/bleger.fr\/weisswein\/"},"modified":"2025-06-14T08:57:05","modified_gmt":"2025-06-14T08:57:05","slug":"weisswein","status":"publish","type":"page","link":"https:\/\/bleger.fr\/de\/weisswein\/","title":{"rendered":"Wei\u00dfwein"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d&#8220; global_colors_info=&#8220;{%22gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d%22:%91%22background_color%22%93}&#8220;][et_pb_row column_structure=&#8220;3_5,2_5&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#FFFFFF&#8220; width=&#8220;90%&#8220; max_width=&#8220;90%&#8220; custom_margin=&#8220;||3%||false|false&#8220; custom_padding=&#8220;0px|0px|0px|3%|true|false&#8220; border_radii=&#8220;off|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;5%|0%|5%|2%|true|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;Lovelace Regular|600|||||||&#8220; header_text_color=&#8220;gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d&#8220; header_font_size=&#8220;14px&#8220; background_color=&#8220;gcid-3611aca6-68b3-47c2-acc5-70e472902818&#8243; module_alignment=&#8220;left&#8220; custom_margin=&#8220;||2%||false|false&#8220; custom_padding=&#8220;10px|25px|0px|25px|false|true&#8220; custom_css_main_element=&#8220;display:inline-block;&#8220; border_radii=&#8220;on|200px|200px|200px|200px&#8220; global_colors_info=&#8220;{%22gcid-3611aca6-68b3-47c2-acc5-70e472902818%22:%91%22background_color%22%93,%22gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d%22:%91%22header_text_color%22%93}&#8220;]<\/p>\n<h1>Wei\u00dfweine aus dem Elsass<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_2_font=&#8220;Nunito|||on|||||&#8220; header_2_text_color=&#8220;#000000&#8243; header_2_font_size=&#8220;40px&#8220; header_2_line_height=&#8220;1.3em&#8220; custom_margin=&#8220;||2%||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Lassen Sie sich von der Finesse unserer Wei\u00dfweine verf\u00fchren.<br \/>\n<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Nunito|600|||||||&#8220; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;16px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Als Symbol des els\u00e4ssischen Know-hows spiegeln unsere Wei\u00dfweine den ganzen Reichtum und die Vielfalt unseres Terroirs wider. <strong>Dank eines biologischen Weinbaus, der die Natur respektiert, und einer sorgf\u00e4ltigen Weinbereitung stellen wir au\u00dfergew\u00f6hnliche Cuv\u00e9es her, die Finesse, Frische und aromatische Komplexit\u00e4t vereinen.<\/strong><\/p>\n<p>Vom lebhaften, mineralischen Riesling \u00fcber den ausdrucksstarken, w\u00fcrzigen Gew\u00fcrztraminer bis hin zum eleganten, strukturierten Pinot Gris &#8211; jede Flasche erz\u00e4hlt eine Geschichte, die von unserer Leidenschaft und unserem Engagement f\u00fcr authentische Weine handelt.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;#vin&#8220; button_text=&#8220;Entdecken Sie&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;6d78355a-bd81-420f-85b9-865e1ad4c17d&#8220; custom_margin=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/Les-vins-blancs-dAlsace-Domaine-BLEGER.webp&#8220; border_radii=&#8220;on|0px|0px|0px|0px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; module_id=&#8220;vin&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; max_width=&#8220;90%&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Sylvaner&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; header_font=&#8220;Lovelace Regular|600|||||||&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;35px&#8220; header_line_height=&#8220;1.2em&#8220; body_font=&#8220;Nunito||||||||&#8220; body_text_color=&#8220;#FFFFFF&#8220; body_line_height=&#8220;1.2em&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0) 0%|#000000 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/sylvaner-vin-d-alsace-1.webp&#8220; transform_translate_linked=&#8220;off&#8220; height=&#8220;500px&#8220; custom_padding=&#8220;75%|10%|8%|10%|false|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ0OTIiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; border_radii=&#8220;off|20px|||&#8220; border_color_all=&#8220;#FFFFFF&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_spread=&#8220;-80px&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; border_radii__hover_enabled=&#8220;off|desktop&#8220; border_radii__hover=&#8220;on|10px|10px|10px|10px&#8220; box_shadow_spread__hover_enabled=&#8220;on|hover&#8220; box_shadow_spread__hover=&#8220;-6px&#8220; border_width_all__hover_enabled=&#8220;on|hover&#8220; border_width_all__hover=&#8220;0px&#8220; content__hover_enabled=&#8220;off|desktop&#8220; content__hover=&#8220;<\/p>\n<p>Pinot blanc, Auxerrois, Riesling, Pinot gris, Muscat, Gewurtztraminer&#8230;<\/p>\n<p><span style=%22color: #99cc00;%22><u>En savoir +<\/u><\/span><\/p>\n<p>&#8220; transform_scale__hover=&#8220;97%|97%&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<p>Bemerkenswert frisch und leicht, mit einer diskreten Fruchtigkeit, er ist angenehm und durstl\u00f6schend und wei\u00df eine sch\u00f6ne Lebendigkeit zu zeigen&#8230;.<\/p>\n<p><span style=\"color: #ffffff;\"><u>mehr erfahren<\/u><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Pinot Blanc&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; header_font=&#8220;Lovelace Regular|600|||||||&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;35px&#8220; header_line_height=&#8220;1.2em&#8220; body_font=&#8220;Nunito||||||||&#8220; body_text_color=&#8220;#FFFFFF&#8220; body_line_height=&#8220;1.2em&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0) 0%|#000000 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/pinot-blanc-vin-d-alsace-1.webp&#8220; transform_translate_linked=&#8220;off&#8220; height=&#8220;500px&#8220; custom_padding=&#8220;75%|10%|8%|10%|false|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1MjAiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; border_radii=&#8220;off||||&#8220; border_color_all=&#8220;#FFFFFF&#8220; border_color_right=&#8220;gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d&#8220; border_color_left=&#8220;gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_spread=&#8220;-80px&#8220; global_colors_info=&#8220;{%22gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d%22:%91%22border_color_left%22,%22border_color_right%22%93}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; border_radii__hover_enabled=&#8220;off|hover&#8220; border_radii__hover=&#8220;on|10px|10px|10px|10px&#8220; box_shadow_spread__hover_enabled=&#8220;on|hover&#8220; box_shadow_spread__hover=&#8220;-6px&#8220; border_width_all__hover_enabled=&#8220;on|hover&#8220; border_width_all__hover=&#8220;0px&#8220; content__hover_enabled=&#8220;off|desktop&#8220; content__hover=&#8220;<\/p>\n<p>Le Ros\u00e9, le Orange, le Rouge et L\u2019\u00e9lev\u00e9 en f\u00fbt de ch\u00eane<\/p>\n<p><span style=%22color: #99cc00;%22><u>En savoir +<\/u><\/span><\/p>\n<p>&#8220; border_width_left__hover_enabled=&#8220;on|hover&#8220; border_width_left__hover=&#8220;4px&#8220; border_width_right__hover_enabled=&#8220;on|hover&#8220; border_width_right__hover=&#8220;4px&#8220; transform_scale__hover=&#8220;97%|97%&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<p>Zart, delikat, Frische und Geschmeidigkeit verbindend, stellt er eine goldene Mitte in der Palette der els\u00e4ssischen Weine dar. Mit einer gro\u00dfen Anpassungsf\u00e4higkeit. <\/p>\n<p><span style=\"color: #ffffff;\"><u>mehr erfahren<\/u><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Auxerrois&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; header_font=&#8220;Lovelace Regular|600|||||||&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;35px&#8220; header_line_height=&#8220;1.2em&#8220; body_font=&#8220;Nunito||||||||&#8220; body_text_color=&#8220;#FFFFFF&#8220; body_line_height=&#8220;1.2em&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0) 0%|#000000 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/auxerrois-vin-d-alsace-1.webp&#8220; transform_translate_linked=&#8220;off&#8220; height=&#8220;500px&#8220; custom_padding=&#8220;75%|10%|8%|10%|false|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1MzMiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; border_radii=&#8220;off||||&#8220; border_color_all=&#8220;#FFFFFF&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_spread=&#8220;-80px&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; border_radii__hover_enabled=&#8220;off|desktop&#8220; border_radii__hover=&#8220;on|10px|10px|10px|10px&#8220; box_shadow_spread__hover_enabled=&#8220;on|hover&#8220; box_shadow_spread__hover=&#8220;-6px&#8220; border_width_all__hover_enabled=&#8220;on|hover&#8220; border_width_all__hover=&#8220;0px&#8220; content__hover_enabled=&#8220;off|desktop&#8220; content__hover=&#8220;Cr\u00e9mant Brut, D\u00e9mi-sec, Extra Brut et Cr\u00e9mant Ros\u00e9 Brut<\/p>\n<p><span style=%22color: #99cc00;%22><u>En savoir +<\/u><\/span>&#8220; transform_scale__hover=&#8220;97%|97%&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<p>Diese Rebsorte wird oft zusammen mit dem Wei\u00dfburgunder vinifiziert, ist aber selten allein. Angenehm, raffiniert und subtil, unterscheidet er sich vom Wei\u00dfburgunder durch seinen geringen S\u00e4uregehalt. <\/p>\n<p><span style=\"color: #ffffff;\"><u>mehr erfahren<\/u><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Riesling&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; header_font=&#8220;Lovelace Regular|600|||||||&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;35px&#8220; header_line_height=&#8220;1.2em&#8220; body_font=&#8220;Nunito||||||||&#8220; body_text_color=&#8220;#FFFFFF&#8220; body_line_height=&#8220;1.2em&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0) 0%|#000000 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/riesling-vin-d-alsace.webp&#8220; transform_translate_linked=&#8220;off&#8220; height=&#8220;500px&#8220; custom_padding=&#8220;75%|10%|8%|10%|false|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1NDAiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; border_radii=&#8220;off||20px||&#8220; border_color_all=&#8220;#FFFFFF&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_spread=&#8220;-80px&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; border_radii__hover_enabled=&#8220;off|desktop&#8220; border_radii__hover=&#8220;on|10px|10px|10px|10px&#8220; box_shadow_spread__hover_enabled=&#8220;on|hover&#8220; box_shadow_spread__hover=&#8220;-6px&#8220; border_width_all__hover_enabled=&#8220;on|hover&#8220; border_width_all__hover=&#8220;0px&#8220; content__hover_enabled=&#8220;off|desktop&#8220; content__hover=&#8220;Cr\u00e9mant Brut, D\u00e9mi-sec, Extra Brut et Cr\u00e9mant Ros\u00e9 Brut<\/p>\n<p><span style=%22color: #99cc00;%22><u>En savoir +<\/u><\/span>&#8220; transform_scale__hover=&#8220;97%|97%&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<p>Trocken, rassig und zart fruchtig bietet er ein Bukett von gro\u00dfer Finesse mit manchmal mineralischen oder blumigen Nuancen, die ihn zu einem ausgezeichneten Lagerwein machen.<\/p>\n<p><span style=\"color: #ffffff;\"><u>mehr erfahren<\/u><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; max_width=&#8220;90%&#8220; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Pinot gris&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; header_font=&#8220;Lovelace Regular|600|||||||&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;35px&#8220; header_line_height=&#8220;1.2em&#8220; body_font=&#8220;Nunito||||||||&#8220; body_text_color=&#8220;#FFFFFF&#8220; body_line_height=&#8220;1.2em&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0) 0%|#000000 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/edelzwicker-vin-blanc-d-alsace.webp&#8220; transform_translate_linked=&#8220;off&#8220; height=&#8220;500px&#8220; custom_padding=&#8220;75%|10%|8%|10%|false|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1NDciLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; border_radii=&#8220;off||||20px&#8220; border_color_all=&#8220;#FFFFFF&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_spread=&#8220;-80px&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; border_radii__hover_enabled=&#8220;off|desktop&#8220; border_radii__hover=&#8220;on|10px|10px|10px|10px&#8220; box_shadow_spread__hover_enabled=&#8220;on|hover&#8220; box_shadow_spread__hover=&#8220;-6px&#8220; border_width_all__hover_enabled=&#8220;on|hover&#8220; border_width_all__hover=&#8220;0px&#8220; content__hover_enabled=&#8220;off|desktop&#8220; content__hover=&#8220;<\/p>\n<p>Le Domaine produit sur ce site prestigieux un Riesling et un Gewurztraminer<\/p>\n<p><span style=%22color: #99cc00;%22><u>En savoir +<\/u><\/span><\/p>\n<p>&#8220; transform_scale__hover=&#8220;97%|97%&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<p>Er ist kr\u00e4ftig, rund und lang im Mund und weist Aromen von Unterholz auf, die manchmal leicht rauchig sind. Er entwickelt eine Opulenz und einen sehr charakteristischen Geschmack. <\/p>\n<p><span style=\"color: #ffffff;\"><u>mehr erfahren<\/u><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Muscat&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; header_font=&#8220;Lovelace Regular|600|||||||&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;35px&#8220; header_line_height=&#8220;1.2em&#8220; body_font=&#8220;Nunito||||||||&#8220; body_text_color=&#8220;#FFFFFF&#8220; body_line_height=&#8220;1.2em&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0) 0%|#000000 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/muscat-vin-d-alsace-1.webp&#8220; transform_translate_linked=&#8220;off&#8220; height=&#8220;500px&#8220; custom_padding=&#8220;75%|10%|8%|10%|false|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1NTEiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; border_radii=&#8220;off||||&#8220; border_color_all=&#8220;#FFFFFF&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_spread=&#8220;-80px&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; border_radii__hover_enabled=&#8220;off|desktop&#8220; border_radii__hover=&#8220;on|10px|10px|10px|10px&#8220; box_shadow_spread__hover_enabled=&#8220;on|hover&#8220; box_shadow_spread__hover=&#8220;-6px&#8220; border_width_all__hover_enabled=&#8220;on|hover&#8220; border_width_all__hover=&#8220;0px&#8220; content__hover_enabled=&#8220;off|desktop&#8220; content__hover=&#8220;<\/p>\n<p>Un vin tr\u00e8s moelleux avec des ar\u00f4mes de surmaturation<\/p>\n<p><span style=%22color: #99cc00;%22><u>En savoir +<\/u><\/span><\/p>\n<p>&#8220; transform_scale__hover=&#8220;97%|97%&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<p>Er ist sehr aromatisch und bringt den Geschmack frischer Fr\u00fcchte wunderbar zum Ausdruck. Er unterscheidet sich von den s\u00fc\u00dfen Muscats des S\u00fcdens durch seinen trockenen Charakter.<\/p>\n<p><span style=\"color: #ffffff;\"><u>mehr erfahren<\/u><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Gewurztraminer&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; header_font=&#8220;Lovelace Regular|600|||||||&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;32px&#8220; header_line_height=&#8220;1.2em&#8220; body_font=&#8220;Nunito||||||||&#8220; body_text_color=&#8220;#FFFFFF&#8220; body_line_height=&#8220;1.2em&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0) 0%|#000000 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/muscat-vin-d-alsace.webp&#8220; transform_translate_linked=&#8220;off&#8220; height=&#8220;500px&#8220; custom_padding=&#8220;75%|10%|8%|10%|false|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1NTciLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; border_radii=&#8220;off||||&#8220; border_color_all=&#8220;#FFFFFF&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_spread=&#8220;-80px&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; border_radii__hover_enabled=&#8220;off|desktop&#8220; border_radii__hover=&#8220;on|10px|10px|10px|10px&#8220; box_shadow_spread__hover_enabled=&#8220;on|hover&#8220; box_shadow_spread__hover=&#8220;-6px&#8220; border_width_all__hover_enabled=&#8220;on|hover&#8220; border_width_all__hover=&#8220;0px&#8220; content__hover_enabled=&#8220;off|desktop&#8220; content__hover=&#8220;<\/p>\n<p>Un vin tr\u00e8s moelleux avec des ar\u00f4mes de surmaturation<\/p>\n<p><span style=%22color: #99cc00;%22><u>En savoir +<\/u><\/span><\/p>\n<p>&#8220; transform_scale__hover=&#8220;97%|97%&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<p>Vollmundig und \u00fcppig, kr\u00e4ftig und verf\u00fchrerisch, manchmal leicht lieblich, ist er der ber\u00fchmteste Wein aus dem Elsass. Sein intensives Bouquet entwickelt reiche Aromen von exotischen Fr\u00fcchten, Blumen oder Gew\u00fcrzen. <\/p>\n<p><span style=\"color: #ffffff;\"><u>mehr erfahren<\/u><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Edelzwicker&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; header_font=&#8220;Lovelace Regular|600|||||||&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;35px&#8220; header_line_height=&#8220;1.2em&#8220; body_font=&#8220;Nunito||||||||&#8220; body_text_color=&#8220;#FFFFFF&#8220; body_line_height=&#8220;1.2em&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0) 0%|#000000 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/gewurztraminer-vin-d-alsace-1.webp&#8220; transform_translate_linked=&#8220;off&#8220; height=&#8220;500px&#8220; custom_padding=&#8220;75%|10%|8%|10%|false|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1NjMiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; border_radii=&#8220;off|||20px|&#8220; border_color_all=&#8220;#FFFFFF&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_spread=&#8220;-80px&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; border_radii__hover_enabled=&#8220;off|desktop&#8220; border_radii__hover=&#8220;on|10px|10px|10px|10px&#8220; box_shadow_spread__hover_enabled=&#8220;on|hover&#8220; box_shadow_spread__hover=&#8220;-6px&#8220; border_width_all__hover_enabled=&#8220;on|hover&#8220; border_width_all__hover=&#8220;0px&#8220; content__hover_enabled=&#8220;off|desktop&#8220; content__hover=&#8220;<\/p>\n<p>Les eaux de vie, les liqueurs et les cr\u00e8mes d\u2019Alsace<\/p>\n<p><span style=%22color: #99cc00;%22><u>En savoir +<\/u><\/span><\/p>\n<p>&#8220; transform_scale__hover=&#8220;97%|97%&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<p>Er ist eine Mischung aus mehreren wei\u00dfen Rebsorten, die harmonisch aufeinander abgestimmt sind und sich je nach Jahrgang stark unterscheiden. Er wird in Ein-Liter-Flaschen verkauft. <\/p>\n<p><span style=\"color: #ffffff;\"><u>mehr erfahren<\/u><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;3_5,2_5&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; max_width=&#8220;90%&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;cebc3c6b-5be3-4642-8f51-86341270038c&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>W\u00e4hlen Sie aus unseren Cuv\u00e9es und lassen Sie sie sich nach Hause schicken.<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; max_width=&#8220;90%&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_shop type=&#8220;product_category&#8220; posts_number=&#8220;30&#8243; include_categories=&#8220;396&#8243; columns_number=&#8220;5&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;bf270719-a208-4f7f-a97b-0da3a5f9b2fd&#8220; price_font=&#8220;Lovelace Regular|600|||||||&#8220; price_font_size=&#8220;18px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_shop][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_enable_color=&#8220;off&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0.5) 0%|rgba(0,0,0,0.67) 99%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/Vente-et-fabrication-de-vin-rouge-rose-en-Alsace-Domaine-BLEGER.webp&#8220; custom_margin=&#8220;||4%||false|false&#8220; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_enable_color=&#8220;off&#8220; width=&#8220;90%&#8220; max_width=&#8220;90%&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;0px|0px|0px|3%|true|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{%22gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d%22:%91%22background_color%22%93}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_enable_color=&#8220;off&#8220; custom_padding=&#8220;2%|0%|2%|2%|true|false&#8220; global_colors_info=&#8220;{%22gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d%22:%91%22background_color%22%93}&#8220;][et_pb_image src=&#8220;https:\/\/bleger.fr\/wp-content\/uploads\/2025\/02\/Logo-Bleger-BLANC-1.svg&#8220; title_text=&#8220;Logo Bl\u00e9ger %91BLANC%93&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;10%&#8220; module_alignment=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_2_font=&#8220;Nunito|700|||||||&#8220; header_2_text_align=&#8220;center&#8220; header_2_text_color=&#8220;#FFFFFF&#8220; header_2_font_size=&#8220;40px&#8220; header_2_line_height=&#8220;1.3em&#8220; background_enable_color=&#8220;off&#8220; custom_margin=&#8220;||0%||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Ein Bekenntnis zu Qualit\u00e4t und Natur<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Nunito|600|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;16px&#8220; ul_line_height=&#8220;1.9em&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p style=\"text-align: center;\">Auf der Domaine Bl\u00e9ger beruht die Exzellenz unserer Weine auf einem tiefen Respekt vor der Natur und einem st\u00e4ndigen Streben nach Qualit\u00e4t. Seit mehreren Generationen bewirtschaften wir unsere Weinberge in Harmonie mit ihrer Umgebung und sind davon \u00fcberzeugt, dass der Reichtum eines Weines in der Erde beginnt, die ihn n\u00e4hrt. Unser Weingut ist f\u00fcr den biologischen Landbau zertifiziert, ein starkes Engagement, das Praktiken garantiert, die den Boden, die biologische Vielfalt und den nat\u00fcrlichen Zyklus der Reben respektieren. Wir bevorzugen nat\u00fcrliche Methoden und verbannen synthetische Pestizide und Herbizide, um die Reinheit unserer Trauben und die Authentizit\u00e4t unserer Terroirs zu bewahren.   <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; max_width=&#8220;90%&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d&#8220; custom_padding=&#8220;1%|2%|2%|2%|false|true&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{%22gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d%22:%91%22background_color%22%93}&#8220;][et_pb_code _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||5%||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<script src=\"https:\/\/cdn.lordicon.com\/lordicon.js\"><\/script><!-- [et_pb_line_break_holder] --><lord-icon src=\"https:\/\/cdn.lordicon.com\/whmqasgs.json\" trigger=\"hover\" colors=\"primary:#96c22c,secondary:#2d2d2d\" style=\"width:60px;height:60px\"><!-- [et_pb_line_break_holder] --><\/lord-icon>[\/et_pb_code][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Nunito||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;1.4em&#8220; header_4_font=&#8220;Lovelace Regular|700|||||||&#8220; header_4_text_color=&#8220;#000000&#8243; header_4_line_height=&#8220;0.6em&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||3%||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4 style=\"text-align: center;\">Eine Weinbereitung,<\/h4>\n<h4 style=\"text-align: center;\">die die Trauben respektiert<\/h4>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;gcid-7549515b-6adb-4dc8-9af4-1abd0cb0998f&#8220; divider_weight=&#8220;1px&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;20%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||-2%||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{%22gcid-7549515b-6adb-4dc8-9af4-1abd0cb0998f%22:%91%22color%22%93}&#8220;][\/et_pb_divider][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Nunito||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;1.4em&#8220; header_4_font=&#8220;Nunito|700|||||||&#8220; header_4_text_color=&#8220;#000000&#8243; header_4_font_size=&#8220;22px&#8220; header_4_line_height=&#8220;0.6em&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Unsere manuelle Weinlese, die nat\u00fcrliche G\u00e4rung und die minimalistische Weinbereitung offenbaren die Authentizit\u00e4t des els\u00e4ssischen Terroirs und bieten reine, ausgewogene und charakterstarke Weine.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d&#8220; custom_padding=&#8220;1%|2%|2%|2%|false|true&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{%22gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d%22:%91%22background_color%22,%22background_color%22%93}&#8220;][et_pb_code _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||5%||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<script src=\"https:\/\/cdn.lordicon.com\/lordicon.js\"><\/script><!-- [et_pb_line_break_holder] --><lord-icon src=\"https:\/\/cdn.lordicon.com\/ycwydima.json\" trigger=\"hover\" colors=\"primary:#96c22c,secondary:#2d2d2d\" style=\"width:60px;height:60px\"><!-- [et_pb_line_break_holder] --><\/lord-icon>[\/et_pb_code][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Nunito||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;1.4em&#8220; header_4_font=&#8220;Lovelace Regular|700|||||||&#8220; header_4_text_color=&#8220;#000000&#8243; header_4_line_height=&#8220;0.6em&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||3%||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4 style=\"text-align: center;\">Nachhaltiger und verantwortungsvoller<\/h4>\n<h4 style=\"text-align: center;\">Weinbau<\/h4>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;gcid-7549515b-6adb-4dc8-9af4-1abd0cb0998f&#8220; divider_weight=&#8220;1px&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;20%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||-2%||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{%22gcid-7549515b-6adb-4dc8-9af4-1abd0cb0998f%22:%91%22color%22%93}&#8220;][\/et_pb_divider][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Nunito||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;1.4em&#8220; header_4_font=&#8220;Nunito|700|||||||&#8220; header_4_text_color=&#8220;#000000&#8243; header_4_font_size=&#8220;22px&#8220; header_4_line_height=&#8220;0.6em&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Wir bewirtschaften unsere Weinberge im Einklang mit den nat\u00fcrlichen Zyklen, indem wir Begr\u00fcnung, Handarbeit und biologische Verfahren f\u00f6rdern und so die Biodiversit\u00e4t und das Gleichgewicht unseres Terroirs bewahren.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d&#8220; custom_padding=&#8220;1%|2%|2%|2%|false|true&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{%22gcid-586e0179-3da4-4405-86cd-c9a2ec12f30d%22:%91%22background_color%22,%22background_color%22%93}&#8220;][et_pb_code _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||5%||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<script src=\"https:\/\/cdn.lordicon.com\/lordicon.js\"><\/script><!-- [et_pb_line_break_holder] --><lord-icon src=\"https:\/\/cdn.lordicon.com\/gemrnilc.json\" trigger=\"hover\" colors=\"primary:#96c22c,secondary:#2d2d2d\" style=\"width:60px;height:60px\"><!-- [et_pb_line_break_holder] --><\/lord-icon>[\/et_pb_code][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Nunito||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;1.4em&#8220; header_4_font=&#8220;Lovelace Regular|700|||||||&#8220; header_4_text_color=&#8220;#000000&#8243; header_4_line_height=&#8220;0.6em&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||3%||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4 style=\"text-align: center;\">Eine kontrollierte<\/h4>\n<h4 style=\"text-align: center;\">Umweltbelastung<\/h4>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;gcid-7549515b-6adb-4dc8-9af4-1abd0cb0998f&#8220; divider_weight=&#8220;1px&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;20%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||-2%||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{%22gcid-7549515b-6adb-4dc8-9af4-1abd0cb0998f%22:%91%22color%22%93}&#8220;][\/et_pb_divider][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Nunito||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;1.4em&#8220; header_4_font=&#8220;Nunito|700|||||||&#8220; header_4_text_color=&#8220;#000000&#8243; header_4_font_size=&#8220;22px&#8220; header_4_line_height=&#8220;0.6em&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;]Wir engagieren uns f\u00fcr eine nachhaltige Zukunft und reduzieren unseren CO2-Fu\u00dfabdruck, indem wir das Wassermanagement optimieren, leichtere Flaschen verwenden und in jeder Phase unserer Produktion umweltvertr\u00e4gliche L\u00f6sungen anwenden.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wei\u00dfweine aus dem ElsassLassen Sie sich von der Finesse unserer Wei\u00dfweine verf\u00fchren. Als Symbol des els\u00e4ssischen Know-hows spiegeln unsere Wei\u00dfweine den ganzen Reichtum und die Vielfalt unseres Terroirs wider. Dank eines biologischen Weinbaus, der die Natur respektiert, und einer sorgf\u00e4ltigen Weinbereitung stellen wir au\u00dfergew\u00f6hnliche Cuv\u00e9es her, die Finesse, Frische und aromatische Komplexit\u00e4t vereinen. Vom lebhaften, mineralischen Riesling \u00fcber den ausdrucksstarken, w\u00fcrzigen Gew\u00fcrztraminer bis hin zum eleganten, strukturierten Pinot Gris &#8211; jede Flasche erz\u00e4hlt eine Geschichte, die von unserer Leidenschaft und unserem Engagement f\u00fcr authentische Weine handelt.Bemerkenswert frisch und leicht, mit einer diskreten Fruchtigkeit, er ist angenehm und durstl\u00f6schend und wei\u00df eine sch\u00f6ne Lebendigkeit zu zeigen&#8230;. mehr erfahrenZart, delikat, Frische und Geschmeidigkeit verbindend, stellt er eine goldene Mitte in der Palette der els\u00e4ssischen Weine dar. Mit einer gro\u00dfen Anpassungsf\u00e4higkeit. mehr erfahrenDiese Rebsorte wird oft zusammen mit dem Wei\u00dfburgunder vinifiziert, ist aber selten allein. Angenehm, raffiniert und subtil, unterscheidet er sich vom Wei\u00dfburgunder durch seinen geringen S\u00e4uregehalt. mehr erfahrenTrocken, rassig und zart fruchtig bietet er ein Bukett von gro\u00dfer Finesse mit manchmal mineralischen oder blumigen Nuancen, die ihn zu einem ausgezeichneten Lagerwein machen. mehr erfahrenEr ist kr\u00e4ftig, rund und lang im Mund und weist Aromen von Unterholz auf, die manchmal leicht rauchig [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-6170","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wei\u00dfwein - Domaine Claude et Christophe Bl\u00e9ger<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bleger.fr\/vin-blanc-d-alsace\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wei\u00dfwein - Domaine Claude et Christophe Bl\u00e9ger\" \/>\n<meta property=\"og:description\" content=\"Wei\u00dfweine aus dem ElsassLassen Sie sich von der Finesse unserer Wei\u00dfweine verf\u00fchren. Als Symbol des els\u00e4ssischen Know-hows spiegeln unsere Wei\u00dfweine den ganzen Reichtum und die Vielfalt unseres Terroirs wider. Dank eines biologischen Weinbaus, der die Natur respektiert, und einer sorgf\u00e4ltigen Weinbereitung stellen wir au\u00dfergew\u00f6hnliche Cuv\u00e9es her, die Finesse, Frische und aromatische Komplexit\u00e4t vereinen. Vom lebhaften, mineralischen Riesling \u00fcber den ausdrucksstarken, w\u00fcrzigen Gew\u00fcrztraminer bis hin zum eleganten, strukturierten Pinot Gris - jede Flasche erz\u00e4hlt eine Geschichte, die von unserer Leidenschaft und unserem Engagement f\u00fcr authentische Weine handelt.Bemerkenswert frisch und leicht, mit einer diskreten Fruchtigkeit, er ist angenehm und durstl\u00f6schend und wei\u00df eine sch\u00f6ne Lebendigkeit zu zeigen.... mehr erfahrenZart, delikat, Frische und Geschmeidigkeit verbindend, stellt er eine goldene Mitte in der Palette der els\u00e4ssischen Weine dar. Mit einer gro\u00dfen Anpassungsf\u00e4higkeit. mehr erfahrenDiese Rebsorte wird oft zusammen mit dem Wei\u00dfburgunder vinifiziert, ist aber selten allein. Angenehm, raffiniert und subtil, unterscheidet er sich vom Wei\u00dfburgunder durch seinen geringen S\u00e4uregehalt. mehr erfahrenTrocken, rassig und zart fruchtig bietet er ein Bukett von gro\u00dfer Finesse mit manchmal mineralischen oder blumigen Nuancen, die ihn zu einem ausgezeichneten Lagerwein machen. mehr erfahrenEr ist kr\u00e4ftig, rund und lang im Mund und weist Aromen von Unterholz auf, die manchmal leicht rauchig [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bleger.fr\/vin-blanc-d-alsace\/\" \/>\n<meta property=\"og:site_name\" content=\"Domaine Claude et Christophe Bl\u00e9ger\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-14T08:57:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"21\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bleger.fr\\\/vin-blanc-d-alsace\\\/\",\"url\":\"https:\\\/\\\/bleger.fr\\\/vin-blanc-d-alsace\\\/\",\"name\":\"Wei\u00dfwein - Domaine Claude et Christophe Bl\u00e9ger\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bleger.fr\\\/#website\"},\"datePublished\":\"2025-02-20T15:11:36+00:00\",\"dateModified\":\"2025-06-14T08:57:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bleger.fr\\\/vin-blanc-d-alsace\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bleger.fr\\\/vin-blanc-d-alsace\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bleger.fr\\\/vin-blanc-d-alsace\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/bleger.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wei\u00dfwein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bleger.fr\\\/#website\",\"url\":\"https:\\\/\\\/bleger.fr\\\/\",\"name\":\"Domaine Claude et Christophe Bl\u00e9ger\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bleger.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wei\u00dfwein - Domaine Claude et Christophe Bl\u00e9ger","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bleger.fr\/vin-blanc-d-alsace\/","og_locale":"de_DE","og_type":"article","og_title":"Wei\u00dfwein - Domaine Claude et Christophe Bl\u00e9ger","og_description":"Wei\u00dfweine aus dem ElsassLassen Sie sich von der Finesse unserer Wei\u00dfweine verf\u00fchren. Als Symbol des els\u00e4ssischen Know-hows spiegeln unsere Wei\u00dfweine den ganzen Reichtum und die Vielfalt unseres Terroirs wider. Dank eines biologischen Weinbaus, der die Natur respektiert, und einer sorgf\u00e4ltigen Weinbereitung stellen wir au\u00dfergew\u00f6hnliche Cuv\u00e9es her, die Finesse, Frische und aromatische Komplexit\u00e4t vereinen. Vom lebhaften, mineralischen Riesling \u00fcber den ausdrucksstarken, w\u00fcrzigen Gew\u00fcrztraminer bis hin zum eleganten, strukturierten Pinot Gris - jede Flasche erz\u00e4hlt eine Geschichte, die von unserer Leidenschaft und unserem Engagement f\u00fcr authentische Weine handelt.Bemerkenswert frisch und leicht, mit einer diskreten Fruchtigkeit, er ist angenehm und durstl\u00f6schend und wei\u00df eine sch\u00f6ne Lebendigkeit zu zeigen.... mehr erfahrenZart, delikat, Frische und Geschmeidigkeit verbindend, stellt er eine goldene Mitte in der Palette der els\u00e4ssischen Weine dar. Mit einer gro\u00dfen Anpassungsf\u00e4higkeit. mehr erfahrenDiese Rebsorte wird oft zusammen mit dem Wei\u00dfburgunder vinifiziert, ist aber selten allein. Angenehm, raffiniert und subtil, unterscheidet er sich vom Wei\u00dfburgunder durch seinen geringen S\u00e4uregehalt. mehr erfahrenTrocken, rassig und zart fruchtig bietet er ein Bukett von gro\u00dfer Finesse mit manchmal mineralischen oder blumigen Nuancen, die ihn zu einem ausgezeichneten Lagerwein machen. mehr erfahrenEr ist kr\u00e4ftig, rund und lang im Mund und weist Aromen von Unterholz auf, die manchmal leicht rauchig [&hellip;]","og_url":"https:\/\/bleger.fr\/vin-blanc-d-alsace\/","og_site_name":"Domaine Claude et Christophe Bl\u00e9ger","article_modified_time":"2025-06-14T08:57:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"21\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bleger.fr\/vin-blanc-d-alsace\/","url":"https:\/\/bleger.fr\/vin-blanc-d-alsace\/","name":"Wei\u00dfwein - Domaine Claude et Christophe Bl\u00e9ger","isPartOf":{"@id":"https:\/\/bleger.fr\/#website"},"datePublished":"2025-02-20T15:11:36+00:00","dateModified":"2025-06-14T08:57:05+00:00","breadcrumb":{"@id":"https:\/\/bleger.fr\/vin-blanc-d-alsace\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bleger.fr\/vin-blanc-d-alsace\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bleger.fr\/vin-blanc-d-alsace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bleger.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Wei\u00dfwein"}]},{"@type":"WebSite","@id":"https:\/\/bleger.fr\/#website","url":"https:\/\/bleger.fr\/","name":"Domaine Claude et Christophe Bl\u00e9ger","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bleger.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/bleger.fr\/de\/wp-json\/wp\/v2\/pages\/6170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bleger.fr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bleger.fr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bleger.fr\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bleger.fr\/de\/wp-json\/wp\/v2\/comments?post=6170"}],"version-history":[{"count":3,"href":"https:\/\/bleger.fr\/de\/wp-json\/wp\/v2\/pages\/6170\/revisions"}],"predecessor-version":[{"id":6839,"href":"https:\/\/bleger.fr\/de\/wp-json\/wp\/v2\/pages\/6170\/revisions\/6839"}],"wp:attachment":[{"href":"https:\/\/bleger.fr\/de\/wp-json\/wp\/v2\/media?parent=6170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}